{"id":3826,"date":"2014-01-23T23:49:45","date_gmt":"2014-01-23T22:49:45","guid":{"rendered":"https:\/\/www.ccaniene.com\/?p=3826"},"modified":"2014-01-23T23:53:31","modified_gmt":"2014-01-23T22:53:31","slug":"un-atleta-al-mese-michele-paoletti","status":"publish","type":"post","link":"https:\/\/www.ccaniene.com\/it_it\/un-atleta-al-mese-michele-paoletti\/","title":{"rendered":"Un atleta al mese: Michele Paoletti"},"content":{"rendered":"<p>Benvenuto Michele<\/p>\n<p>Ho conosciuto Michele in occasione del mondiale maxi del 2009, regata a cui partecipammo armando la barca del consocio Filippo Faruffini e che vincemmo per pochi secondi.<\/p>\n<p>Mi colp\u00ec quanto disse di lui Vascotto: \u2019 \u2026\u00e8 sicuramente il pi\u00f9 forte velista italiano\u2026\u2019<\/p>\n<p>La strada di Michele si \u00e8 spesso incrociata con la nostra, infatti \u00e8 il marito di Giovanna Micol , la nostra atleta\u00a0 olimpica di 470 ora in corsa per RIO 2016 in equipaggio con Rufo Bressani nella classe Nacra.<\/p>\n<p>Michi , gi\u00e0 olimpico sul soling a Sydney, non era riuscito a qualificarsi con il finn per l\u2019 olimpiade di Londra ed\u00a0 abbiamo vissuto\u00a0 l\u2019emozione olimpica da spettatori.<\/p>\n<p>Cosi \u00e8 nata la nostra amicizia ,mi confess\u00f2 di voler abbandonare la vela olimpica per consolidare la sua famiglia\u00a0 e per dedicarsi alla professione insieme a Giovi ,entrambi\u00a0 Architetti.<\/p>\n<p>Ma la vita consente delle accelerazioni imprevedibili, \u00e8 arrivata Olivia , la loro figlia, e dopo appena un anno eccoli tornare entrambi in acqua , pronti al ritorno dagli allenamenti a svezzarla.<\/p>\n<p>Pensate ad una famiglia tipo e poi sentite come vivono i due archi velisti. Michi adesso \u00e8 a Miami , Giovi \u00e8 stata fino a domenica scorsa ad Anzio con la piccola, alle 6 accudiva la bimba ,alle 8,30 in acqua, 11,30 ristoro ,13 in acqua , 17 dalla bimba momentaneamente lasciata ad una nonna.<\/p>\n<p>Ma il bello arriva a febbraio marzo, infatti il programma prevede il trasferimento della famiglia Paoletti a Palma de Majorca ad allenarsi in vista della prima tappa del circuito europeo della coppa del mondo , a quando anche Olivia allo stecco?<\/p>\n<p>Il portale del GIORNALE DELLA VELA ha dedicato un bell&#8217;articolo a Michele, di seguito il link:<\/p>\n<p><a href=\"http:\/\/www.giornaledellavela.com\/news\/2014\/01\/16\/storie-di-velisti-michele-paoletti-un-benjamin-button-verso-rio-2016\/\" target=\"_blank\">http:\/\/www.giornaledellavela.com\/news\/2014\/01\/16\/storie-di-velisti-michele-paoletti-un-benjamin-button-verso-rio-2016\/<\/a><\/p>\n<p>Giancarlo Gianni<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Benvenuto Michele Ho conosciuto Michele in occasione del mondiale maxi del 2009, regata a cui partecipammo armando la barca del consocio Filippo Faruffini e che vincemmo per pochi secondi. Mi colp\u00ec quanto disse di lui Vascotto: \u2019 \u2026\u00e8 sicuramente il pi\u00f9 forte velista italiano\u2026\u2019 La strada di Michele si \u00e8 spesso incrociata con la nostra, [&hellip;]<\/p>\n","protected":false},"author":4667,"featured_media":3829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2,26],"tags":[],"class_list":["post-3826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-vela","pmpro-has-access"],"featured_image_urls":{"woocommerce_thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-300x300.jpg","woocommerce_gallery_thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-100x100.jpg","woocommerce_single":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-600x424.jpg","thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-200x200.jpg","medium":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-460x325.jpg","medium_large":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-768x543.jpg","large":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-980x692.jpg","second":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-270x246.jpg","single-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-870x450.jpg","large-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-780x450.jpg","medium-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-390x225.jpg","large-archive-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-570x300.jpg","small-archive-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-300x200.jpg","portrait-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-300x212.jpg","portrait":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-870x615.jpg","gallery":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi-270x270.jpg"},"appp_media":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un atleta al mese: Michele Paoletti - Circolo Canottieri Aniene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.ccaniene.com\/it_it\/un-atleta-al-mese-michele-paoletti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un atleta al mese: Michele Paoletti - Circolo Canottieri Aniene\" \/>\n<meta property=\"og:description\" content=\"Benvenuto Michele Ho conosciuto Michele in occasione del mondiale maxi del 2009, regata a cui partecipammo armando la barca del consocio Filippo Faruffini e che vincemmo per pochi secondi. Mi colp\u00ec quanto disse di lui Vascotto: \u2019 \u2026\u00e8 sicuramente il pi\u00f9 forte velista italiano\u2026\u2019 La strada di Michele si \u00e8 spesso incrociata con la nostra, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.ccaniene.com\/it_it\/un-atleta-al-mese-michele-paoletti\/\" \/>\n<meta property=\"og:site_name\" content=\"Circolo Canottieri Aniene\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-23T22:49:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-01-23T22:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1754\" \/>\n\t<meta property=\"og:image:height\" content=\"1239\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/\",\"url\":\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/\",\"name\":\"Un atleta al mese: Michele Paoletti - Circolo Canottieri Aniene\",\"isPartOf\":{\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg\",\"datePublished\":\"2014-01-23T22:49:45+00:00\",\"dateModified\":\"2014-01-23T22:53:31+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#primaryimage\",\"url\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg\",\"contentUrl\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg\",\"width\":1754,\"height\":1239},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ccaniene.com\/it_it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un atleta al mese: Michele Paoletti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\",\"url\":\"https:\/\/www.ccaniene.com\/it_it\/\",\"name\":\"Circolo Canottieri Aniene\",\"description\":\"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.ccaniene.com\/it_it\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un atleta al mese: Michele Paoletti - Circolo Canottieri Aniene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.ccaniene.com\/it_it\/un-atleta-al-mese-michele-paoletti\/","og_locale":"it_IT","og_type":"article","og_title":"Un atleta al mese: Michele Paoletti - Circolo Canottieri Aniene","og_description":"Benvenuto Michele Ho conosciuto Michele in occasione del mondiale maxi del 2009, regata a cui partecipammo armando la barca del consocio Filippo Faruffini e che vincemmo per pochi secondi. Mi colp\u00ec quanto disse di lui Vascotto: \u2019 \u2026\u00e8 sicuramente il pi\u00f9 forte velista italiano\u2026\u2019 La strada di Michele si \u00e8 spesso incrociata con la nostra, [&hellip;]","og_url":"http:\/\/www.ccaniene.com\/it_it\/un-atleta-al-mese-michele-paoletti\/","og_site_name":"Circolo Canottieri Aniene","article_published_time":"2014-01-23T22:49:45+00:00","article_modified_time":"2014-01-23T22:53:31+00:00","og_image":[{"width":1754,"height":1239,"url":"http:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/","url":"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/","name":"Un atleta al mese: Michele Paoletti - Circolo Canottieri Aniene","isPartOf":{"@id":"https:\/\/www.ccaniene.com\/it_it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#primaryimage"},"image":{"@id":"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg","datePublished":"2014-01-23T22:49:45+00:00","dateModified":"2014-01-23T22:53:31+00:00","author":{"@id":""},"breadcrumb":{"@id":"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#primaryimage","url":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg","contentUrl":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/michi-e-giovi.jpg","width":1754,"height":1239},{"@type":"BreadcrumbList","@id":"http:\/\/www.ccaniene.com\/un-atleta-al-mese-michele-paoletti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccaniene.com\/it_it\/"},{"@type":"ListItem","position":2,"name":"Un atleta al mese: Michele Paoletti"}]},{"@type":"WebSite","@id":"https:\/\/www.ccaniene.com\/it_it\/#website","url":"https:\/\/www.ccaniene.com\/it_it\/","name":"Circolo Canottieri Aniene","description":"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"","url":"https:\/\/www.ccaniene.com\/it_it\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts\/3826"}],"collection":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/users\/4667"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/comments?post=3826"}],"version-history":[{"count":1,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts\/3826\/revisions"}],"predecessor-version":[{"id":3827,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts\/3826\/revisions\/3827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/media\/3829"}],"wp:attachment":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/media?parent=3826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/categories?post=3826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/tags?post=3826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}