{"id":3798,"date":"2014-01-08T22:57:36","date_gmt":"2014-01-08T21:57:36","guid":{"rendered":"https:\/\/www.ccaniene.com\/?p=3798"},"modified":"2014-01-08T22:57:36","modified_gmt":"2014-01-08T21:57:36","slug":"fantastica-aniene","status":"publish","type":"post","link":"https:\/\/www.ccaniene.com\/it_it\/fantastica-aniene\/","title":{"rendered":"FANTASTICA ANIENE"},"content":{"rendered":"<p>Il racconto del consocio responsabile della sezione vela d&#8217;altura Alessandro Maria Rinaldi pubblicato su Yacht Capital: la splendida avventura del Tp52, secondo posto alla Barcolana.<\/p>\n<p><a href=\"http:\/\/www.ccaniene.com\/wp-content\/uploads\/2014\/01\/Fantastica-Aniene-YC-dic13.pdf\">Fantastica Aniene YC dic13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il racconto del consocio responsabile della sezione vela d&#8217;altura Alessandro Maria Rinaldi pubblicato su Yacht Capital: la splendida avventura del Tp52, secondo posto alla Barcolana. Fantastica Aniene YC dic13<\/p>\n","protected":false},"author":4667,"featured_media":3187,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2,26],"tags":[],"class_list":["post-3798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-vela","pmpro-has-access"],"featured_image_urls":{"woocommerce_thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-300x300.jpg","woocommerce_gallery_thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-100x100.jpg","woocommerce_single":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-600x540.jpg","thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-200x200.jpg","medium":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-460x414.jpg","medium_large":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-768x691.jpg","large":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-980x881.jpg","second":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-270x246.jpg","single-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-870x450.jpg","large-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-780x450.jpg","medium-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-390x225.jpg","large-archive-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-570x300.jpg","small-archive-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-300x200.jpg","portrait-thumb":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-300x270.jpg","portrait":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-870x782.jpg","gallery":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura-270x270.jpg"},"appp_media":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FANTASTICA ANIENE - Circolo Canottieri Aniene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.ccaniene.com\/it_it\/fantastica-aniene\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FANTASTICA ANIENE - Circolo Canottieri Aniene\" \/>\n<meta property=\"og:description\" content=\"Il racconto del consocio responsabile della sezione vela d&#8217;altura Alessandro Maria Rinaldi pubblicato su Yacht Capital: la splendida avventura del Tp52, secondo posto alla Barcolana. Fantastica Aniene YC dic13\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.ccaniene.com\/it_it\/fantastica-aniene\/\" \/>\n<meta property=\"og:site_name\" content=\"Circolo Canottieri Aniene\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-08T21:57:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"2124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.ccaniene.com\/fantastica-aniene\/\",\"url\":\"http:\/\/www.ccaniene.com\/fantastica-aniene\/\",\"name\":\"FANTASTICA ANIENE - Circolo Canottieri Aniene\",\"isPartOf\":{\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.ccaniene.com\/fantastica-aniene\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.ccaniene.com\/fantastica-aniene\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg\",\"datePublished\":\"2014-01-08T21:57:36+00:00\",\"dateModified\":\"2014-01-08T21:57:36+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.ccaniene.com\/fantastica-aniene\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.ccaniene.com\/fantastica-aniene\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/www.ccaniene.com\/fantastica-aniene\/#primaryimage\",\"url\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg\",\"contentUrl\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg\",\"width\":2362,\"height\":2124},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.ccaniene.com\/fantastica-aniene\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ccaniene.com\/it_it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FANTASTICA ANIENE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\",\"url\":\"https:\/\/www.ccaniene.com\/it_it\/\",\"name\":\"Circolo Canottieri Aniene\",\"description\":\"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.ccaniene.com\/it_it\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FANTASTICA ANIENE - Circolo Canottieri Aniene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.ccaniene.com\/it_it\/fantastica-aniene\/","og_locale":"it_IT","og_type":"article","og_title":"FANTASTICA ANIENE - Circolo Canottieri Aniene","og_description":"Il racconto del consocio responsabile della sezione vela d&#8217;altura Alessandro Maria Rinaldi pubblicato su Yacht Capital: la splendida avventura del Tp52, secondo posto alla Barcolana. Fantastica Aniene YC dic13","og_url":"http:\/\/www.ccaniene.com\/it_it\/fantastica-aniene\/","og_site_name":"Circolo Canottieri Aniene","article_published_time":"2014-01-08T21:57:36+00:00","og_image":[{"width":2362,"height":2124,"url":"http:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.ccaniene.com\/fantastica-aniene\/","url":"http:\/\/www.ccaniene.com\/fantastica-aniene\/","name":"FANTASTICA ANIENE - Circolo Canottieri Aniene","isPartOf":{"@id":"https:\/\/www.ccaniene.com\/it_it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.ccaniene.com\/fantastica-aniene\/#primaryimage"},"image":{"@id":"http:\/\/www.ccaniene.com\/fantastica-aniene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg","datePublished":"2014-01-08T21:57:36+00:00","dateModified":"2014-01-08T21:57:36+00:00","author":{"@id":""},"breadcrumb":{"@id":"http:\/\/www.ccaniene.com\/fantastica-aniene\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.ccaniene.com\/fantastica-aniene\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.ccaniene.com\/fantastica-aniene\/#primaryimage","url":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg","contentUrl":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2013\/08\/logo_vela_altura.jpg","width":2362,"height":2124},{"@type":"BreadcrumbList","@id":"http:\/\/www.ccaniene.com\/fantastica-aniene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccaniene.com\/it_it\/"},{"@type":"ListItem","position":2,"name":"FANTASTICA ANIENE"}]},{"@type":"WebSite","@id":"https:\/\/www.ccaniene.com\/it_it\/#website","url":"https:\/\/www.ccaniene.com\/it_it\/","name":"Circolo Canottieri Aniene","description":"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"","url":"https:\/\/www.ccaniene.com\/it_it\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts\/3798"}],"collection":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/users\/4667"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/comments?post=3798"}],"version-history":[{"count":1,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts\/3798\/revisions"}],"predecessor-version":[{"id":3800,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/posts\/3798\/revisions\/3800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/media\/3187"}],"wp:attachment":[{"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/media?parent=3798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/categories?post=3798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccaniene.com\/it_it\/wp-json\/wp\/v2\/tags?post=3798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}