{"id":7371,"date":"2015-01-14T17:05:22","date_gmt":"2015-01-14T16:05:22","guid":{"rendered":"https:\/\/www.ccaniene.com\/?p=7371"},"modified":"2015-01-14T17:05:22","modified_gmt":"2015-01-14T16:05:22","slug":"simone-bolelli-atp-sydney-australia","status":"publish","type":"post","link":"https:\/\/www.ccaniene.com\/en\/simone-bolelli-atp-sydney-australia\/","title":{"rendered":"SIMONE BOLELLI &#8211; ATP SYDNEY ( AUSTRALIA)"},"content":{"rendered":"<p>Grande risultato per Simone Bolelli al torneo ATP di Sydney in corso di svolgimento sui campi in cemento dell\u2019Oyimpic Park Tennis Center della citt\u00e0 australiana.<\/p>\n<p>Il nostro giocatore, dopo aver agevolmente superato il primo turno del tabellone principale, ha sconfitto nettamente il belga Goffin, n. 22 del ranking mondiale, con il punteggio di 63 63.<\/p>\n<p>Prossimo avversario per Simone sar\u00e0 il serbo Victor Troickj ex n. 12 ATP.<\/p>","protected":false},"excerpt":{"rendered":"<p>Grande risultato per Simone Bolelli al torneo ATP di Sydney in corso di svolgimento sui campi in cemento dell\u2019Oyimpic Park Tennis Center della citt\u00e0 australiana. Il nostro giocatore, dopo aver agevolmente superato il primo turno del tabellone principale, ha sconfitto nettamente il belga Goffin, n. 22 del ranking mondiale, con il punteggio di 63 63. [&hellip;]<\/p>","protected":false},"author":4667,"featured_media":7372,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2,10],"tags":[],"class_list":["post-7371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-tennis","pmpro-has-access"],"featured_image_urls":{"woocommerce_thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image-300x300.jpg","woocommerce_gallery_thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image-100x100.jpg","woocommerce_single":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image-600x324.jpg","thumbnail":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image-400x334.jpg"},"appp_media":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SIMONE BOLELLI - ATP SYDNEY ( AUSTRALIA) - Circolo Canottieri Aniene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccaniene.com\/en\/simone-bolelli-atp-sydney-australia\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SIMONE BOLELLI - ATP SYDNEY ( AUSTRALIA) - Circolo Canottieri Aniene\" \/>\n<meta property=\"og:description\" content=\"Grande risultato per Simone Bolelli al torneo ATP di Sydney in corso di svolgimento sui campi in cemento dell\u2019Oyimpic Park Tennis Center della citt\u00e0 australiana. Il nostro giocatore, dopo aver agevolmente superato il primo turno del tabellone principale, ha sconfitto nettamente il belga Goffin, n. 22 del ranking mondiale, con il punteggio di 63 63. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccaniene.com\/en\/simone-bolelli-atp-sydney-australia\/\" \/>\n<meta property=\"og:site_name\" content=\"Circolo Canottieri Aniene\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-14T16:05:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"618\" \/>\n\t<meta property=\"og:image:height\" content=\"334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/\",\"url\":\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/\",\"name\":\"SIMONE BOLELLI - ATP SYDNEY ( AUSTRALIA) - Circolo Canottieri Aniene\",\"isPartOf\":{\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg\",\"datePublished\":\"2015-01-14T16:05:22+00:00\",\"dateModified\":\"2015-01-14T16:05:22+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#primaryimage\",\"url\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg\",\"contentUrl\":\"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg\",\"width\":618,\"height\":334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ccaniene.com\/it_it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SIMONE BOLELLI &#8211; ATP SYDNEY ( AUSTRALIA)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\",\"url\":\"https:\/\/www.ccaniene.com\/it_it\/\",\"name\":\"Circolo Canottieri Aniene\",\"description\":\"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.ccaniene.com\/en\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SIMONE BOLELLI - ATP SYDNEY ( AUSTRALIA) - Circolo Canottieri Aniene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccaniene.com\/en\/simone-bolelli-atp-sydney-australia\/","og_locale":"en_GB","og_type":"article","og_title":"SIMONE BOLELLI - ATP SYDNEY ( AUSTRALIA) - Circolo Canottieri Aniene","og_description":"Grande risultato per Simone Bolelli al torneo ATP di Sydney in corso di svolgimento sui campi in cemento dell\u2019Oyimpic Park Tennis Center della citt\u00e0 australiana. Il nostro giocatore, dopo aver agevolmente superato il primo turno del tabellone principale, ha sconfitto nettamente il belga Goffin, n. 22 del ranking mondiale, con il punteggio di 63 63. [&hellip;]","og_url":"https:\/\/www.ccaniene.com\/en\/simone-bolelli-atp-sydney-australia\/","og_site_name":"Circolo Canottieri Aniene","article_published_time":"2015-01-14T16:05:22+00:00","og_image":[{"width":618,"height":334,"url":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/","url":"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/","name":"SIMONE BOLELLI - ATP SYDNEY ( AUSTRALIA) - Circolo Canottieri Aniene","isPartOf":{"@id":"https:\/\/www.ccaniene.com\/it_it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#primaryimage"},"image":{"@id":"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg","datePublished":"2015-01-14T16:05:22+00:00","dateModified":"2015-01-14T16:05:22+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#primaryimage","url":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg","contentUrl":"https:\/\/www.ccaniene.com\/wp-content\/uploads\/2015\/01\/image.jpg","width":618,"height":334},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccaniene.com\/simone-bolelli-atp-sydney-australia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccaniene.com\/it_it\/"},{"@type":"ListItem","position":2,"name":"SIMONE BOLELLI &#8211; ATP SYDNEY ( AUSTRALIA)"}]},{"@type":"WebSite","@id":"https:\/\/www.ccaniene.com\/it_it\/#website","url":"https:\/\/www.ccaniene.com\/it_it\/","name":"Circolo Canottieri Aniene","description":"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"","url":"https:\/\/www.ccaniene.com\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/posts\/7371"}],"collection":[{"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/users\/4667"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/comments?post=7371"}],"version-history":[{"count":1,"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/posts\/7371\/revisions"}],"predecessor-version":[{"id":7373,"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/posts\/7371\/revisions\/7373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/media\/7372"}],"wp:attachment":[{"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/media?parent=7371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/categories?post=7371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/tags?post=7371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}