{"id":52,"date":"2008-11-10T00:00:00","date_gmt":"2008-11-10T00:00:00","guid":{"rendered":""},"modified":"2008-11-10T00:00:00","modified_gmt":"2008-11-10T00:00:00","slug":"regate-internazionali-kinder-skiff-e-silver-skiff","status":"publish","type":"post","link":"http:\/\/www.ccaniene.com\/en\/regate-internazionali-kinder-skiff-e-silver-skiff\/","title":{"rendered":"Regate Internazionali Kinder Skiff e Silver Skiff"},"content":{"rendered":"<p>Il Circolo Canottieri Aniene ha partecipato con 3 allievi, 2 cadetti e 1 senior alle Regate Internazionali Kinder Skiff e Silver Skiff tenutesi sabato 8 e domenica 9 novembre 2008. Buoni i risultati per gli atleti del Circolo.<\/p>\n<p><!--more--><\/p>\n<div align=\"center\">ALESSANDRO ROCCHEGIANI<\/div>\n<div align=\"center\">4\u00b0 POSTO<\/div>\n<div align=\"center\">ANDREA MORICONI<br \/>8\u00b0 POSTO<\/div>\n<div align=\"center\">RENATA DUSMET<br \/>8\u00b0 POSTO<\/div>\n<div align=\"center\">LUCA DI FRANCESCO<br \/>21\u00b0 POSTO<\/div>\n<div align=\"center\">LUCA SANTORO<br \/>27\u00b0 POSTO<\/div>\n<div align=\"center\">RAFFAELLO LEONARDO<br \/>7\u00b0 POSTO<\/div>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Il Circolo Canottieri Aniene ha partecipato con 3 allievi, 2 cadetti e 1 senior alle Regate Internazionali Kinder Skiff e Silver Skiff tenutesi sabato 8 e domenica 9 novembre 2008. Buoni i risultati per gli atleti del Circolo.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"pmpro_default_level":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[13],"tags":[],"class_list":["post-52","post","type-post","status-publish","format-standard","hentry","category-altri-sport","pmpro-has-access"],"featured_image_urls":{},"appp_media":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Regate Internazionali Kinder Skiff e Silver Skiff - Circolo Canottieri Aniene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccaniene.com\/en\/regate-internazionali-kinder-skiff-e-silver-skiff\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regate Internazionali Kinder Skiff e Silver Skiff - Circolo Canottieri Aniene\" \/>\n<meta property=\"og:description\" content=\"Il Circolo Canottieri Aniene ha partecipato con 3 allievi, 2 cadetti e 1 senior alle Regate Internazionali Kinder Skiff e Silver Skiff tenutesi sabato 8 e domenica 9 novembre 2008. Buoni i risultati per gli atleti del Circolo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccaniene.com\/en\/regate-internazionali-kinder-skiff-e-silver-skiff\/\" \/>\n<meta property=\"og:site_name\" content=\"Circolo Canottieri Aniene\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-10T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ccaniene.com\/wp-content\/uploads\/2008\/02\/DSC_0354_1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/\",\"url\":\"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/\",\"name\":\"Regate Internazionali Kinder Skiff e Silver Skiff - Circolo Canottieri Aniene\",\"isPartOf\":{\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\"},\"datePublished\":\"2008-11-10T00:00:00+00:00\",\"dateModified\":\"2008-11-10T00:00:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ccaniene.com\/it_it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regate Internazionali Kinder Skiff e Silver Skiff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ccaniene.com\/it_it\/#website\",\"url\":\"https:\/\/www.ccaniene.com\/it_it\/\",\"name\":\"Circolo Canottieri Aniene\",\"description\":\"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\/\/www.ccaniene.com\/en\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regate Internazionali Kinder Skiff e Silver Skiff - Circolo Canottieri Aniene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccaniene.com\/en\/regate-internazionali-kinder-skiff-e-silver-skiff\/","og_locale":"en_GB","og_type":"article","og_title":"Regate Internazionali Kinder Skiff e Silver Skiff - Circolo Canottieri Aniene","og_description":"Il Circolo Canottieri Aniene ha partecipato con 3 allievi, 2 cadetti e 1 senior alle Regate Internazionali Kinder Skiff e Silver Skiff tenutesi sabato 8 e domenica 9 novembre 2008. Buoni i risultati per gli atleti del Circolo.","og_url":"https:\/\/www.ccaniene.com\/en\/regate-internazionali-kinder-skiff-e-silver-skiff\/","og_site_name":"Circolo Canottieri Aniene","article_published_time":"2008-11-10T00:00:00+00:00","og_image":[{"width":960,"height":639,"url":"http:\/\/www.ccaniene.com\/wp-content\/uploads\/2008\/02\/DSC_0354_1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/","url":"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/","name":"Regate Internazionali Kinder Skiff e Silver Skiff - Circolo Canottieri Aniene","isPartOf":{"@id":"https:\/\/www.ccaniene.com\/it_it\/#website"},"datePublished":"2008-11-10T00:00:00+00:00","dateModified":"2008-11-10T00:00:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccaniene.com\/it_it\/regate-internazionali-kinder-skiff-e-silver-skiff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccaniene.com\/it_it\/"},{"@type":"ListItem","position":2,"name":"Regate Internazionali Kinder Skiff e Silver Skiff"}]},{"@type":"WebSite","@id":"https:\/\/www.ccaniene.com\/it_it\/#website","url":"https:\/\/www.ccaniene.com\/it_it\/","name":"Circolo Canottieri Aniene","description":"Collare d&#039;Oro e Stella d&#039;Oro al Merito Sportivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccaniene.com\/it_it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"","url":"http:\/\/www.ccaniene.com\/en\/author\/"}]}},"_links":{"self":[{"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/posts\/52"}],"collection":[{"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":0,"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/posts\/52\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/categories?post=52"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.ccaniene.com\/en\/wp-json\/wp\/v2\/tags?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}